
{"id":12008,"date":"2024-09-25T18:30:42","date_gmt":"2024-09-25T21:30:42","guid":{"rendered":"https:\/\/africaatual.com.br\/?p=12008"},"modified":"2024-10-07T11:52:53","modified_gmt":"2024-10-07T14:52:53","slug":"noticias-africanas-23","status":"publish","type":"post","link":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/","title":{"rendered":"Not\u00edcias Africanas #23"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12008\" class=\"elementor elementor-12008\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e19c1f6 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"e19c1f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f7f7ec7 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"f7f7ec7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d240eb3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d240eb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Not\u00edcias Africanas <br>\nConex\u00f5es Brasil e \u00c1fricas<br>\nN\u00famero 23 - Setembro\/2024\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd68de0 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"fd68de0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-43ed921 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"43ed921\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b49fa48 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b49fa48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Estilistas africanas deslumbram na Fashion Week de Nova York<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-436ee38 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"436ee38\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-691d53d elementor-widget elementor-widget-image\" data-id=\"691d53d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"461\" src=\"https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Praca-e-Orla-em-Luanda-Angola-1024x461.jpg\" class=\"attachment-large size-large wp-image-12010\" alt=\"Imagem de um grande grupo de pessoas vestindo camisetas e bon\u00e9s brancos, participando de uma atividade coletiva ao ar livre em uma pra\u00e7a na cidade de Luanda, Angola. Ao fundo, h\u00e1 altos pr\u00e9dios modernos, palmeiras e uma \u00e1rea urbana em desenvolvimento. O grupo parece estar organizado em fileiras, realizando alongamentos ou outra atividade f\u00edsica em conjunto.\" srcset=\"https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Praca-e-Orla-em-Luanda-Angola-1024x461.jpg 1024w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Praca-e-Orla-em-Luanda-Angola-300x135.jpg 300w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Praca-e-Orla-em-Luanda-Angola-768x346.jpg 768w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Praca-e-Orla-em-Luanda-Angola-1536x691.jpg 1536w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Praca-e-Orla-em-Luanda-Angola-2048x922.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b4e3e65 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b4e3e65\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c4a4d0d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"c4a4d0d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f650aa7 elementor-widget elementor-widget-text-editor\" data-id=\"f650aa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"c-article-summary\" style=\"text-align: justify;\">As trajet\u00f3rias empreendedoras de Yvonne Afrostreet e da African Fabric &amp;amp; Designs<br \/>Kenya simbolizam a resili\u00eancia, criatividade e vis\u00e3o que impulsionam o sucesso no<br \/>cen\u00e1rio global da moda contempor\u00e2nea. Saindo de origens modestas no Qu\u00eania para<br \/>conquistar as passarelas de Nova Iorque, ambas est\u00e3o reformulando a narrativa da moda<br \/>africana e do empreendedorismo, desafiando estere\u00f3tipos e provando que o mundo est\u00e1<br \/>pronto para abra\u00e7ar a criatividade africana em seus pr\u00f3prios termos. Essas marcas, ao<br \/>incorporarem elementos culturais \u00fanicos, t\u00eam destacado o potencial da moda africana<br \/>para influenciar e inovar no mercado internacional.<br \/>Fonte da mat\u00e9ria com fotos do desfile voc\u00ea encontra em:<br \/><a href=\"https:\/\/africanvibes.com\/kenyan-fashion-designer-at-new-york-fashion-week\/\">https:\/\/africanvibes.com\/kenyan-fashion-designer-at-new-york-fashion-week\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82bca5f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"82bca5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-197e12d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"197e12d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2bafe9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d2bafe9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tecnologia digital<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c5572a e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2c5572a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0feb82 elementor-widget elementor-widget-image\" data-id=\"d0feb82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"823\" height=\"1024\" src=\"https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Webinar-Africa-Tech-823x1024.jpg\" class=\"attachment-large size-large wp-image-12012\" alt=\"Convite para o webinar de capacita\u00e7\u00e3o em FinTech organizado pela Africa FinTech Network, em colabora\u00e7\u00e3o com Digital Jewels Africa, com o tema: &quot;Navegar e Cumprir Regulamentos&quot;, focando em padr\u00f5es internacionais e estruturas da ind\u00fastria para promover uma cultura de transpar\u00eancia e responsabilidade. A imagem destaca os palestrantes: Ken Njoroge (Co-fundador\/Diretor da Cellulant, Qu\u00eania) como orador principal. Njoki Muthuri (MD\/CEO, Mamlaka Hub and Spoke, Qu\u00eania) como painelista. Deogratius Stephen Massawe (MD, BKTechHouse, Ruanda) como painelista. Hosts: Dr. Patrick Saidu Conteh (CEO, Africa Fintech Network). Adedoyin Odunfa (MD\/CEO, Digital Jewels Africa). O evento ser\u00e1 realizado no dia 24 de setembro de 2024, das 11h \u00e0s 13h (EAT).\" srcset=\"https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Webinar-Africa-Tech-823x1024.jpg 823w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Webinar-Africa-Tech-241x300.jpg 241w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Webinar-Africa-Tech-768x956.jpg 768w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Webinar-Africa-Tech.jpg 868w\" sizes=\"(max-width: 823px) 100vw, 823px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9570db1 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"9570db1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c471540 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"c471540\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-367deaf elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"367deaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aconteceu em setembro um importante webin\u00e1rio sobre Fintechs no continente<br \/>africano. Os debates e iniciativas avan\u00e7am em projetos inovadores. Os estudos e<br \/>aplicativos de padr\u00f5es internacionais impactam as estruturas industriais locais e<br \/>regionais, promovendo uma cultura de transpar\u00eancia e responsabilidade social e<br \/>empresarial.<\/p><p>Fonte da informa\u00e7\u00e3o:<br \/><a href=\"https:\/\/mail.yahoo.com\/d\/search\/referrer=unread&amp;keyword=is%253Aunread&amp;accountIds=1&amp;excludefolders=ARCHIVE\/messages\/42936?.intl=br&amp;.lang=pt-BR&amp;pspid=2114710002&amp;activity=header-mail&amp;guce_referrer=aHR0cHM6Ly9sb2dpbi55YWhvby5jb20v&amp;guce_referrer_sig=AQAAAKUDpLmawc0uqKy8NorB-_LzGt5nU2Dw-SJJ91F0sxCWekzU1YiOqIXZ8Fyp45EYjcsSdn-gU00NvPtTMhYOjl30oszukdds3380JxVj5VraAZfkvpHUatZBrLmhGl_m2aj80JbitIrboUGoJfusakKz09zAeIMQW9_lj_AGc2wJ\">https:\/\/mail.yahoo.com\/d\/search\/referrer=unread&amp;amp;keyword=is%253Aunread&amp;amp;accountIds=1&amp;amp;excludefolders=ARCHIVE\/messages\/42936?.intl=br&amp;amp;.lang=pt-BR&amp;amp;pspid=2114710002&amp;amp;activity=header-mail&amp;amp;guce_referrer=aHR0cHM6Ly9sb2dpbi55YWhvby5jb20v&amp;amp;guce_referrer_sig=AQAAAKUDpLmawc0uqKy8NorB-_LzGt5nU2Dw-SJJ91F0sxCWekzU1YiOqIXZ8Fyp45EYjcsSdn-gU00NvPtTMhYOjl30oszukdds3380JxVj5VraAZfkvpHUatZBrLmhGl_m2aj80JbitIrboUGoJfusakKz09zAeIMQW9_lj_AGc2wJ<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a6e43d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"6a6e43d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1bb2629 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"1bb2629\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61847c2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"61847c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Turismo em \u00c1frica \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b85bea e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1b85bea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9896a5b elementor-widget elementor-widget-image\" data-id=\"9896a5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/08\/Projeto-Escolar-02-horizontal-d-1024x576.webp\" class=\"attachment-large size-large wp-image-11828\" alt=\"\" srcset=\"https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/08\/Projeto-Escolar-02-horizontal-d-1024x576.webp 1024w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/08\/Projeto-Escolar-02-horizontal-d-300x169.webp 300w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/08\/Projeto-Escolar-02-horizontal-d-768x432.webp 768w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/08\/Projeto-Escolar-02-horizontal-d-1536x864.webp 1536w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/08\/Projeto-Escolar-02-horizontal-d-800x450.webp 800w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/08\/Projeto-Escolar-02-horizontal-d.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Foto: Prof. Odair Marques<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0f8266 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b0f8266\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abab056 elementor-widget elementor-widget-text-editor\" data-id=\"abab056\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Lan\u00e7amos na plataforma Nutror um curso digital gratuito denominado \u201cTurismo em \u00c1frica\u201d. A proposta inicial \u00e9 oferecer aos professores e estudantes dicas sobre como planejar uma viagem a um pa\u00eds africano. Certamente, n\u00e3o \u00e9 pretens\u00e3o dos v\u00eddeos do curso sanar todas as d\u00favidas, mas, de forma leve, mostrar imagens e dicas sobre situa\u00e7\u00f5es de viagem e informa\u00e7\u00f5es sobre algumas cidades africanas. Assim, tamb\u00e9m motivar os participantes do curso a viajarem a, pelo menos, um ou dois pa\u00edses, para amplia\u00e7\u00e3o de seu repert\u00f3rio cultural pessoal. S\u00e3o 6 v\u00eddeos de 10 minutos cada, em m\u00e9dia. Um curso curto, que pode ser utilizado em sala de aula para atividades e pr\u00e1ticas sobre a profiss\u00e3o de agente de turismo, ou mesmo para a singela apresenta\u00e7\u00e3o de informa\u00e7\u00f5es e conhecimentos sobre alguns detalhes de cidades africanas.<\/span><\/p><p><span style=\"font-weight: 400;\">Ao final do curso os participantes recebem, automaticamente, seu certificado em formato digital.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Link para o curso gratuito, na p\u00e1gina do site <\/span><a href=\"http:\/\/www.africaatual.com.br\"><span style=\"font-weight: 400;\">www.africaatual.com.br<\/span><\/a><span style=\"font-weight: 400;\">:\u00a0<\/span><\/p><p><a href=\"https:\/\/africaatual.com.br\/index.php\/cursos-e-palestras\/\"><span style=\"font-weight: 400;\">https:\/\/africaatual.com.br\/index.php\/cursos-e-palestras\/<\/span><\/a><\/p><p><span style=\"font-weight: 400;\">A expectativa \u00e9 que se promovam novas pesquisas a partir do material apresentado e que ocorram boas rodas de conversa sobre os temas abordados.<\/span><\/p><p><span style=\"font-weight: 400;\">Foto: @prof.odairmarques<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3baa4c0 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3baa4c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b8482e7 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"b8482e7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca4f9b9 elementor-widget elementor-widget-text-editor\" data-id=\"ca4f9b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><i><span style=\"font-weight: 400;\">Surpreenda-se semanalmente com <\/span><\/i><b><i>Not\u00edcias Africanas em Conex\u00f5es Brasil e \u00c1fricas. Publicadas em <\/i><\/b><a href=\"http:\/\/www.africaatual.com.br\"><b><i>www.africaatual.com.br<\/i><\/b><\/a><b><i>. Adquira o Atlas Geocultural da \u00c1frica e amplie o leque de suas informa\u00e7\u00f5es.\u00a0 \u00a0<\/i><\/b><\/p>\n<p><b><i>Voc\u00ea deseja subs\u00eddios para atividades em sala de aula?\u00a0<\/i><\/b><\/p>\n<p><b><i>Fa\u00e7a um dos cursos propostos no <\/i><\/b><a href=\"https:\/\/africaatual.com.br\/index.php\/cursos-e-palestras\/\"><span style=\"font-weight: 400;\">https:\/\/africaatual.com.br\/index.php\/cursos-e-palestras\/<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14f4926 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"14f4926\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-eb5f711 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"eb5f711\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-803664e elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"803664e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Este boletim de not\u00edcias se insere no contexto do Projeto \u00c1frica Atual. Sua postagem ser\u00e1 semanal, \u00e0s quintas-feiras, no site <\/span><a href=\"http:\/\/www.africaatual.com.br\"><span style=\"font-weight: 400;\">www.africaatual.com.br<\/span><\/a><span style=\"font-weight: 400;\">. Outros espa\u00e7os de informa\u00e7\u00e3o: \u00c1frica Atual TV no Youtube, <\/span><a href=\"http:\/\/www.editoraeiros.com.br\"><span style=\"font-weight: 400;\">www.editoraeiros.com.br<\/span><\/a><span style=\"font-weight: 400;\"> e m\u00eddias digitais coligadas. O prop\u00f3sito do boletim est\u00e1 em facilitar a sua pesquisa por informa\u00e7\u00f5es inovadoras sobre os pa\u00edses africanos.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Alertamos que n\u00e3o somos uma ag\u00eancia de not\u00edcias. Nosso prop\u00f3sito se adequa ao selecionar uma breve colet\u00e2nea de informa\u00e7\u00f5es inovadoras, por vezes n\u00e3o publicadas em m\u00eddias brasileiras, apresentando a voc\u00ea os <\/span><i><span style=\"font-weight: 400;\">links<\/span><\/i><span style=\"font-weight: 400;\"> das fontes de informa\u00e7\u00e3o, aproximando os leitores brasileiros de fontes africanas, facilitando pesquisas, subs\u00eddios \u00e0s suas atividades e iniciativas escolares.\u00a0\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>O site \u00c1frica Atual acaba de publicar uma nova atualiza\u00e7\u00e3o com os principais acontecimentos do continente. Fique por dentro das novidades sobre pol\u00edtica, economia, cultura e tecnologia na \u00c1frica.<\/p>\n","protected":false},"author":2,"featured_media":12036,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"inline_featured_image":false,"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","omw_enable_modal_window":"enable","h5ap_radio_sources":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[48,85,1,104,45,62,14],"tags":[230,231,232],"palavra-chave":[],"class_list":["post-12008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","category-atualidades","category-blog","category-escolas","category-industria","category-news","category-noticias","tag-estilistas-africanas","tag-tecnologia-digital","tag-turismo-em-africa","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Not\u00edcias Africanas #23 - africaatual.com.br<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Not\u00edcias Africanas #23 - africaatual.com.br\" \/>\n<meta property=\"og:description\" content=\"O site \u00c1frica Atual acaba de publicar uma nova atualiza\u00e7\u00e3o com os principais acontecimentos do continente. Fique por dentro das novidades sobre pol\u00edtica, economia, cultura e tecnologia na \u00c1frica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/\" \/>\n<meta property=\"og:site_name\" content=\"africaatual.com.br\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-25T21:30:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-07T14:52:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Imagem-do-WhatsApp-de-2024-09-25-as-18.35.33_46191c60.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Isabel Xavier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabel Xavier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/\"},\"author\":{\"name\":\"Isabel Xavier\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#\\\/schema\\\/person\\\/275270ccd0d657af28fbd625ba218b9e\"},\"headline\":\"Not\u00edcias Africanas #23\",\"datePublished\":\"2024-09-25T21:30:42+00:00\",\"dateModified\":\"2024-10-07T14:52:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/\"},\"wordCount\":655,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Imagem-do-WhatsApp-de-2024-09-25-as-18.35.33_46191c60.jpg\",\"keywords\":[\"Estilistas africanas\",\"Tecnologia digital\",\"Turismo em \u00c1frica\"],\"articleSection\":[\"A Africa\",\"Atualidades\",\"Blog\",\"Escolas\",\"Ind\u00fastria\",\"News\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/\",\"url\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/\",\"name\":\"Not\u00edcias Africanas #23 - africaatual.com.br\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Imagem-do-WhatsApp-de-2024-09-25-as-18.35.33_46191c60.jpg\",\"datePublished\":\"2024-09-25T21:30:42+00:00\",\"dateModified\":\"2024-10-07T14:52:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/#primaryimage\",\"url\":\"https:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Imagem-do-WhatsApp-de-2024-09-25-as-18.35.33_46191c60.jpg\",\"contentUrl\":\"https:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Imagem-do-WhatsApp-de-2024-09-25-as-18.35.33_46191c60.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"A imagem cont\u00e9m um card com o t\u00edtulo \\\"NOT\u00cdCIAS AFRICANAS #23\\\", seguido pelo destaque: \\\"Estilistas africanas deslumbram na Fashion Week de Nova York\\\". H\u00e1 tamb\u00e9m a men\u00e7\u00e3o de outras not\u00edcias, como \\\"webin\u00e1rio sobre Fintechs no continente africano e o Projeto Escolar Turismo em \u00c1frica\\\". A parte inferior do card exibe o perfil de Instagram \\\"@atlasgeoculturaldaafrica\\\" e o site \\\"www.africaatual.com.br\\\". Ao fundo da imagem, h\u00e1 uma foto de pessoas vestidas de branco em uma grande pra\u00e7a com pr\u00e9dios altos e modernos ao redor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2024\\\/09\\\/25\\\/noticias-africanas-23\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/africaatual.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias Africanas #23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#website\",\"url\":\"https:\\\/\\\/africaatual.com.br\\\/\",\"name\":\"africaatual.com.br\",\"description\":\"O Atlas Geocultural da \u00c1frica \u00e9 um rico material de leitura e pesquisa, que visa apresentar de forma atual os pa\u00edses africanos, ainda t\u00e3o pouco conhecidos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/africaatual.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#organization\",\"name\":\"africaatual.com.br\",\"url\":\"https:\\\/\\\/africaatual.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/LOGOEIROS_Prancheta-1-tipo-preto.png\",\"contentUrl\":\"http:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/LOGOEIROS_Prancheta-1-tipo-preto.png\",\"width\":1667,\"height\":730,\"caption\":\"africaatual.com.br\"},\"image\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#\\\/schema\\\/person\\\/275270ccd0d657af28fbd625ba218b9e\",\"name\":\"Isabel Xavier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a917370c365d1c248cd5fe4fc02ff6a26d8a5ef7f28c3c7e41757c19a93a954b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a917370c365d1c248cd5fe4fc02ff6a26d8a5ef7f28c3c7e41757c19a93a954b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a917370c365d1c248cd5fe4fc02ff6a26d8a5ef7f28c3c7e41757c19a93a954b?s=96&d=mm&r=g\",\"caption\":\"Isabel Xavier\"},\"url\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/author\\\/webdesign-yta\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Not\u00edcias Africanas #23 - africaatual.com.br","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/","og_locale":"pt_BR","og_type":"article","og_title":"Not\u00edcias Africanas #23 - africaatual.com.br","og_description":"O site \u00c1frica Atual acaba de publicar uma nova atualiza\u00e7\u00e3o com os principais acontecimentos do continente. Fique por dentro das novidades sobre pol\u00edtica, economia, cultura e tecnologia na \u00c1frica.","og_url":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/","og_site_name":"africaatual.com.br","article_published_time":"2024-09-25T21:30:42+00:00","article_modified_time":"2024-10-07T14:52:53+00:00","og_image":[{"width":1080,"height":1080,"url":"http:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Imagem-do-WhatsApp-de-2024-09-25-as-18.35.33_46191c60.jpg","type":"image\/jpeg"}],"author":"Isabel Xavier","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Isabel Xavier","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/#article","isPartOf":{"@id":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/"},"author":{"name":"Isabel Xavier","@id":"https:\/\/africaatual.com.br\/#\/schema\/person\/275270ccd0d657af28fbd625ba218b9e"},"headline":"Not\u00edcias Africanas #23","datePublished":"2024-09-25T21:30:42+00:00","dateModified":"2024-10-07T14:52:53+00:00","mainEntityOfPage":{"@id":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/"},"wordCount":655,"commentCount":0,"publisher":{"@id":"https:\/\/africaatual.com.br\/#organization"},"image":{"@id":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/#primaryimage"},"thumbnailUrl":"https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Imagem-do-WhatsApp-de-2024-09-25-as-18.35.33_46191c60.jpg","keywords":["Estilistas africanas","Tecnologia digital","Turismo em \u00c1frica"],"articleSection":["A Africa","Atualidades","Blog","Escolas","Ind\u00fastria","News","Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/","url":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/","name":"Not\u00edcias Africanas #23 - africaatual.com.br","isPartOf":{"@id":"https:\/\/africaatual.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/#primaryimage"},"image":{"@id":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/#primaryimage"},"thumbnailUrl":"https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Imagem-do-WhatsApp-de-2024-09-25-as-18.35.33_46191c60.jpg","datePublished":"2024-09-25T21:30:42+00:00","dateModified":"2024-10-07T14:52:53+00:00","breadcrumb":{"@id":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/#primaryimage","url":"https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Imagem-do-WhatsApp-de-2024-09-25-as-18.35.33_46191c60.jpg","contentUrl":"https:\/\/africaatual.com.br\/wp-content\/uploads\/2024\/09\/Imagem-do-WhatsApp-de-2024-09-25-as-18.35.33_46191c60.jpg","width":1080,"height":1080,"caption":"A imagem cont\u00e9m um card com o t\u00edtulo \"NOT\u00cdCIAS AFRICANAS #23\", seguido pelo destaque: \"Estilistas africanas deslumbram na Fashion Week de Nova York\". H\u00e1 tamb\u00e9m a men\u00e7\u00e3o de outras not\u00edcias, como \"webin\u00e1rio sobre Fintechs no continente africano e o Projeto Escolar Turismo em \u00c1frica\". A parte inferior do card exibe o perfil de Instagram \"@atlasgeoculturaldaafrica\" e o site \"www.africaatual.com.br\". Ao fundo da imagem, h\u00e1 uma foto de pessoas vestidas de branco em uma grande pra\u00e7a com pr\u00e9dios altos e modernos ao redor"},{"@type":"BreadcrumbList","@id":"https:\/\/africaatual.com.br\/index.php\/2024\/09\/25\/noticias-africanas-23\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/africaatual.com.br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias Africanas #23"}]},{"@type":"WebSite","@id":"https:\/\/africaatual.com.br\/#website","url":"https:\/\/africaatual.com.br\/","name":"africaatual.com.br","description":"O Atlas Geocultural da \u00c1frica \u00e9 um rico material de leitura e pesquisa, que visa apresentar de forma atual os pa\u00edses africanos, ainda t\u00e3o pouco conhecidos.","publisher":{"@id":"https:\/\/africaatual.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/africaatual.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/africaatual.com.br\/#organization","name":"africaatual.com.br","url":"https:\/\/africaatual.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/africaatual.com.br\/#\/schema\/logo\/image\/","url":"http:\/\/africaatual.com.br\/wp-content\/uploads\/2023\/06\/LOGOEIROS_Prancheta-1-tipo-preto.png","contentUrl":"http:\/\/africaatual.com.br\/wp-content\/uploads\/2023\/06\/LOGOEIROS_Prancheta-1-tipo-preto.png","width":1667,"height":730,"caption":"africaatual.com.br"},"image":{"@id":"https:\/\/africaatual.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/africaatual.com.br\/#\/schema\/person\/275270ccd0d657af28fbd625ba218b9e","name":"Isabel Xavier","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a917370c365d1c248cd5fe4fc02ff6a26d8a5ef7f28c3c7e41757c19a93a954b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a917370c365d1c248cd5fe4fc02ff6a26d8a5ef7f28c3c7e41757c19a93a954b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a917370c365d1c248cd5fe4fc02ff6a26d8a5ef7f28c3c7e41757c19a93a954b?s=96&d=mm&r=g","caption":"Isabel Xavier"},"url":"https:\/\/africaatual.com.br\/index.php\/author\/webdesign-yta\/"}]}},"_links":{"self":[{"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12008"}],"version-history":[{"count":9,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12008\/revisions"}],"predecessor-version":[{"id":12037,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12008\/revisions\/12037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/media\/12036"}],"wp:attachment":[{"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12008"},{"taxonomy":"palavra-chave","embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/palavra-chave?post=12008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}