
{"id":1336,"date":"2020-08-19T08:34:50","date_gmt":"2020-08-19T11:34:50","guid":{"rendered":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/"},"modified":"2020-08-19T08:34:50","modified_gmt":"2020-08-19T11:34:50","slug":"danca-negra-contemporanea-existimos-logo-dancamos","status":"publish","type":"post","link":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/","title":{"rendered":"DAN\u00c7A NEGRA CONTEMPOR\u00c2NEA &#8211; EXISTIMOS, LOGO DAN\u00c7AMOS."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1336\" class=\"elementor elementor-1336\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0b1af4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e0b1af4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a538c26\" data-id=\"a538c26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36c328e elementor-widget elementor-widget-text-editor\" data-id=\"36c328e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Artigo de autoria de:\u00a0<\/p><p>Carlos A. V. Soares (Carlos Kiss) e Priscila Luiza Coscarella.<\/p><p>Que tamb\u00e9m cedem as imagens postadas.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80611f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"80611f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c84f75\" data-id=\"4c84f75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6caef74 elementor-widget elementor-widget-text-editor\" data-id=\"6caef74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O objetivo deste trabalho \u00e9 propor reflex\u00f5es sobre a Dan\u00e7a Negra Contempor\u00e2nea e sua contribui\u00e7\u00e3o para a dan\u00e7a brasileira. Propomos reflex\u00f5es de suas caracter\u00edsticas, t\u00e9cnicas e filosofia, elementos fundamentais para a constru\u00e7\u00e3o da corporeidade na dan\u00e7a negra contempor\u00e2nea. O preconceito, a falta de conhecimento e interesse pela dan\u00e7a negra contempor\u00e2nea, s\u00e3o causas de sua segrega\u00e7\u00e3o. Estas inquieta\u00e7\u00f5es foram constru\u00eddas a partir de referenciais te\u00f3ricos e principalmente da mem\u00f3ria corporal de 40 anos de experi\u00eancia em dan\u00e7a de Carlos Kiss. Lembramos a importante contribui\u00e7\u00e3o de core\u00f3grafos e bailarinos na constru\u00e7\u00e3o da dan\u00e7a negra, afro-contempor\u00e2nea e da dan\u00e7a contempor\u00e2nea brasileira, como Mercedes Baptista,Walter Ribeiro, Gilberto de Assis, Paulo da Concei\u00e7\u00e3o, Delegado, Augusto de Omulu, Ismael Ivo, Clyde Morgan, Rubens Barbot, Eus\u00e9bio Lobo, Inaicira Falc\u00e3o, Mestre King.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a028f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9a028f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-735fb60\" data-id=\"735fb60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bb4eb8 elementor-widget elementor-widget-image\" data-id=\"2bb4eb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"480\" src=\"https:\/\/africaatual.com.br\/wp-content\/uploads\/2020\/08\/d-1.jpeg\" class=\"attachment-large size-large wp-image-1341\" alt=\"\" srcset=\"https:\/\/africaatual.com.br\/wp-content\/uploads\/2020\/08\/d-1.jpeg 720w, https:\/\/africaatual.com.br\/wp-content\/uploads\/2020\/08\/d-1-300x200.jpeg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fabf156 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"fabf156\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-333412c\" data-id=\"333412c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41422d1 elementor-widget elementor-widget-text-editor\" data-id=\"41422d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>NOSSA DAN\u00c7A, NOSSO MUNDO.<\/p><p>\u00c9 evidente que a Dan\u00e7a Negra Contempor\u00e2nea n\u00e3o esta isenta das influ\u00eancias de outras dan\u00e7as e vice-versa. O que estamos enfatizando \u00e9 que a ess\u00eancia da Dan\u00e7a Negra Contempor\u00e2nea \u00e9 a t\u00e9cnica de dan\u00e7a negra, constru\u00edda pelas popula\u00e7\u00f5es negras.<\/p><p>\u00a0<\/p><p>A import\u00e2ncia da individualidade do corpo do bailarino e do core\u00f3grafo na dan\u00e7a est\u00e1 relacionada com a eterna procura da humanidade, do seu ser, do pertencimento. Construindo e desconstruindo seu espa\u00e7o, tempo, ritmo, corpo, corporeidade e dan\u00e7a.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-961d980 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"961d980\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a25f65d\" data-id=\"a25f65d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bea7ed1 elementor-widget elementor-widget-text-editor\" data-id=\"bea7ed1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Baixe o artigo integral desta mat\u00e9ria em:\u00a0 \u00a0\u00a0<a href=\"httpss:\/\/africaatual.com.br\/wp-content\/uploads\/2020\/08\/Danca-Negra-Contemporanea-1.pdf\" target=\"_blank\" rel=\"noopener\">DAN\u00c7A NEGRA\u00a0<\/a>C<a href=\"httpss:\/\/africaatual.com.br\/wp-content\/uploads\/2020\/08\/Danca-Negra-Contemporanea-1.pdf\">ONTEMPOR\u00c2NEA<\/a><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Artigo de autoria de:&nbsp; Carlos A. V. Soares (Carlos Kiss) e Priscila Luiza Coscarella. Que tamb\u00e9m cedem as imagens postadas.&nbsp; O objetivo deste trabalho \u00e9 propor reflex\u00f5es sobre a Dan\u00e7a Negra Contempor\u00e2nea e sua contribui\u00e7\u00e3o para a dan\u00e7a brasileira. Propomos reflex\u00f5es de suas caracter\u00edsticas, t\u00e9cnicas e filosofia, elementos fundamentais para a constru\u00e7\u00e3o da corporeidade na dan\u00e7a negra contempor\u00e2nea. O preconceito, a falta de conhecimento e interesse pela dan\u00e7a negra contempor\u00e2nea, s\u00e3o causas de sua segrega\u00e7\u00e3o. Estas inquieta\u00e7\u00f5es foram constru\u00eddas a partir de referenciais te\u00f3ricos e principalmente da mem\u00f3ria corporal de 40 anos de experi\u00eancia em dan\u00e7a de Carlos Kiss. Lembramos a importante contribui\u00e7\u00e3o de core\u00f3grafos e bailarinos na constru\u00e7\u00e3o da dan\u00e7a negra, afro-contempor\u00e2nea e da dan\u00e7a contempor\u00e2nea brasileira, como Mercedes Baptista,Walter Ribeiro, Gilberto de Assis, Paulo da Concei\u00e7\u00e3o, Delegado, Augusto de Omulu, Ismael Ivo, Clyde Morgan, Rubens Barbot, Eus\u00e9bio Lobo, Inaicira Falc\u00e3o, Mestre King. NOSSA DAN\u00c7A, NOSSO MUNDO. \u00c9 evidente que a Dan\u00e7a Negra Contempor\u00e2nea n\u00e3o esta isenta das influ\u00eancias de outras dan\u00e7as e vice-versa. O que estamos enfatizando \u00e9 que a ess\u00eancia da Dan\u00e7a Negra Contempor\u00e2nea \u00e9 a t\u00e9cnica de dan\u00e7a negra, constru\u00edda pelas popula\u00e7\u00f5es negras. A import\u00e2ncia da individualidade do corpo do bailarino e do core\u00f3grafo na dan\u00e7a est\u00e1 relacionada com a eterna procura da humanidade, do seu ser, do pertencimento. Construindo e desconstruindo seu espa\u00e7o, tempo, ritmo, corpo, corporeidade e dan\u00e7a. Baixe o artigo integral desta mat\u00e9ria em:&nbsp; &nbsp;&nbsp;DAN\u00c7A NEGRA&nbsp;CONTEMPOR\u00c2NEA<\/p>\n","protected":false},"author":1,"featured_media":1337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","omw_enable_modal_window":"enable","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[48],"tags":[],"palavra-chave":[],"class_list":["post-1336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DAN\u00c7A NEGRA CONTEMPOR\u00c2NEA - EXISTIMOS, LOGO DAN\u00c7AMOS. - africaatual.com.br<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAN\u00c7A NEGRA CONTEMPOR\u00c2NEA - EXISTIMOS, LOGO DAN\u00c7AMOS. - africaatual.com.br\" \/>\n<meta property=\"og:description\" content=\"Artigo de autoria de:&nbsp; Carlos A. V. Soares (Carlos Kiss) e Priscila Luiza Coscarella. Que tamb\u00e9m cedem as imagens postadas.&nbsp; O objetivo deste trabalho \u00e9 propor reflex\u00f5es sobre a Dan\u00e7a Negra Contempor\u00e2nea e sua contribui\u00e7\u00e3o para a dan\u00e7a brasileira. Propomos reflex\u00f5es de suas caracter\u00edsticas, t\u00e9cnicas e filosofia, elementos fundamentais para a constru\u00e7\u00e3o da corporeidade na dan\u00e7a negra contempor\u00e2nea. O preconceito, a falta de conhecimento e interesse pela dan\u00e7a negra contempor\u00e2nea, s\u00e3o causas de sua segrega\u00e7\u00e3o. Estas inquieta\u00e7\u00f5es foram constru\u00eddas a partir de referenciais te\u00f3ricos e principalmente da mem\u00f3ria corporal de 40 anos de experi\u00eancia em dan\u00e7a de Carlos Kiss. Lembramos a importante contribui\u00e7\u00e3o de core\u00f3grafos e bailarinos na constru\u00e7\u00e3o da dan\u00e7a negra, afro-contempor\u00e2nea e da dan\u00e7a contempor\u00e2nea brasileira, como Mercedes Baptista,Walter Ribeiro, Gilberto de Assis, Paulo da Concei\u00e7\u00e3o, Delegado, Augusto de Omulu, Ismael Ivo, Clyde Morgan, Rubens Barbot, Eus\u00e9bio Lobo, Inaicira Falc\u00e3o, Mestre King. NOSSA DAN\u00c7A, NOSSO MUNDO. \u00c9 evidente que a Dan\u00e7a Negra Contempor\u00e2nea n\u00e3o esta isenta das influ\u00eancias de outras dan\u00e7as e vice-versa. O que estamos enfatizando \u00e9 que a ess\u00eancia da Dan\u00e7a Negra Contempor\u00e2nea \u00e9 a t\u00e9cnica de dan\u00e7a negra, constru\u00edda pelas popula\u00e7\u00f5es negras. A import\u00e2ncia da individualidade do corpo do bailarino e do core\u00f3grafo na dan\u00e7a est\u00e1 relacionada com a eterna procura da humanidade, do seu ser, do pertencimento. Construindo e desconstruindo seu espa\u00e7o, tempo, ritmo, corpo, corporeidade e dan\u00e7a. Baixe o artigo integral desta mat\u00e9ria em:&nbsp; &nbsp;&nbsp;DAN\u00c7A NEGRA&nbsp;CONTEMPOR\u00c2NEA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/\" \/>\n<meta property=\"og:site_name\" content=\"africaatual.com.br\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-19T11:34:50+00:00\" \/>\n<meta property=\"og:image\" content=\"\" \/>\n<meta name=\"author\" content=\"africaatual\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"africaatual\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/\"},\"author\":{\"name\":\"africaatual\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#\\\/schema\\\/person\\\/31315b203b16bec551dcad6d14ff6b17\"},\"headline\":\"DAN\u00c7A NEGRA CONTEMPOR\u00c2NEA &#8211; EXISTIMOS, LOGO DAN\u00c7AMOS.\",\"datePublished\":\"2020-08-19T11:34:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/\"},\"wordCount\":299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/d2.jpeg\",\"articleSection\":[\"A Africa\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/\",\"url\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/\",\"name\":\"DAN\u00c7A NEGRA CONTEMPOR\u00c2NEA - EXISTIMOS, LOGO DAN\u00c7AMOS. - africaatual.com.br\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/d2.jpeg\",\"datePublished\":\"2020-08-19T11:34:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/d2.jpeg\",\"contentUrl\":\"https:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/d2.jpeg\",\"width\":960,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/2020\\\/08\\\/19\\\/danca-negra-contemporanea-existimos-logo-dancamos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/africaatual.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAN\u00c7A NEGRA CONTEMPOR\u00c2NEA &#8211; EXISTIMOS, LOGO DAN\u00c7AMOS.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#website\",\"url\":\"https:\\\/\\\/africaatual.com.br\\\/\",\"name\":\"africaatual.com.br\",\"description\":\"O Atlas Geocultural da \u00c1frica \u00e9 um rico material de leitura e pesquisa, que visa apresentar de forma atual os pa\u00edses africanos, ainda t\u00e3o pouco conhecidos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/africaatual.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#organization\",\"name\":\"africaatual.com.br\",\"url\":\"https:\\\/\\\/africaatual.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/LOGOEIROS_Prancheta-1-tipo-preto.png\",\"contentUrl\":\"http:\\\/\\\/africaatual.com.br\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/LOGOEIROS_Prancheta-1-tipo-preto.png\",\"width\":1667,\"height\":730,\"caption\":\"africaatual.com.br\"},\"image\":{\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/africaatual.com.br\\\/#\\\/schema\\\/person\\\/31315b203b16bec551dcad6d14ff6b17\",\"name\":\"africaatual\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62aeeba3c7bd20a0a9ee0e00da31fba130446f5c08871cd9335ec9bce29b9030?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62aeeba3c7bd20a0a9ee0e00da31fba130446f5c08871cd9335ec9bce29b9030?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62aeeba3c7bd20a0a9ee0e00da31fba130446f5c08871cd9335ec9bce29b9030?s=96&d=mm&r=g\",\"caption\":\"africaatual\"},\"sameAs\":[\"http:\\\/\\\/africaatual.com.br\"],\"url\":\"https:\\\/\\\/africaatual.com.br\\\/index.php\\\/author\\\/atlasgeoculturalafricaatual-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAN\u00c7A NEGRA CONTEMPOR\u00c2NEA - EXISTIMOS, LOGO DAN\u00c7AMOS. - africaatual.com.br","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/","og_locale":"pt_BR","og_type":"article","og_title":"DAN\u00c7A NEGRA CONTEMPOR\u00c2NEA - EXISTIMOS, LOGO DAN\u00c7AMOS. - africaatual.com.br","og_description":"Artigo de autoria de:&nbsp; Carlos A. V. Soares (Carlos Kiss) e Priscila Luiza Coscarella. Que tamb\u00e9m cedem as imagens postadas.&nbsp; O objetivo deste trabalho \u00e9 propor reflex\u00f5es sobre a Dan\u00e7a Negra Contempor\u00e2nea e sua contribui\u00e7\u00e3o para a dan\u00e7a brasileira. Propomos reflex\u00f5es de suas caracter\u00edsticas, t\u00e9cnicas e filosofia, elementos fundamentais para a constru\u00e7\u00e3o da corporeidade na dan\u00e7a negra contempor\u00e2nea. O preconceito, a falta de conhecimento e interesse pela dan\u00e7a negra contempor\u00e2nea, s\u00e3o causas de sua segrega\u00e7\u00e3o. Estas inquieta\u00e7\u00f5es foram constru\u00eddas a partir de referenciais te\u00f3ricos e principalmente da mem\u00f3ria corporal de 40 anos de experi\u00eancia em dan\u00e7a de Carlos Kiss. Lembramos a importante contribui\u00e7\u00e3o de core\u00f3grafos e bailarinos na constru\u00e7\u00e3o da dan\u00e7a negra, afro-contempor\u00e2nea e da dan\u00e7a contempor\u00e2nea brasileira, como Mercedes Baptista,Walter Ribeiro, Gilberto de Assis, Paulo da Concei\u00e7\u00e3o, Delegado, Augusto de Omulu, Ismael Ivo, Clyde Morgan, Rubens Barbot, Eus\u00e9bio Lobo, Inaicira Falc\u00e3o, Mestre King. NOSSA DAN\u00c7A, NOSSO MUNDO. \u00c9 evidente que a Dan\u00e7a Negra Contempor\u00e2nea n\u00e3o esta isenta das influ\u00eancias de outras dan\u00e7as e vice-versa. O que estamos enfatizando \u00e9 que a ess\u00eancia da Dan\u00e7a Negra Contempor\u00e2nea \u00e9 a t\u00e9cnica de dan\u00e7a negra, constru\u00edda pelas popula\u00e7\u00f5es negras. A import\u00e2ncia da individualidade do corpo do bailarino e do core\u00f3grafo na dan\u00e7a est\u00e1 relacionada com a eterna procura da humanidade, do seu ser, do pertencimento. Construindo e desconstruindo seu espa\u00e7o, tempo, ritmo, corpo, corporeidade e dan\u00e7a. Baixe o artigo integral desta mat\u00e9ria em:&nbsp; &nbsp;&nbsp;DAN\u00c7A NEGRA&nbsp;CONTEMPOR\u00c2NEA","og_url":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/","og_site_name":"africaatual.com.br","article_published_time":"2020-08-19T11:34:50+00:00","og_image":[{"url":"httpsss:\/\/africaatual.com.br\/wp-content\/uploads\/2020\/08\/d-1.jpeg","type":"","width":"","height":""}],"author":"africaatual","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"africaatual","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/#article","isPartOf":{"@id":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/"},"author":{"name":"africaatual","@id":"https:\/\/africaatual.com.br\/#\/schema\/person\/31315b203b16bec551dcad6d14ff6b17"},"headline":"DAN\u00c7A NEGRA CONTEMPOR\u00c2NEA &#8211; EXISTIMOS, LOGO DAN\u00c7AMOS.","datePublished":"2020-08-19T11:34:50+00:00","mainEntityOfPage":{"@id":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/"},"wordCount":299,"commentCount":0,"publisher":{"@id":"https:\/\/africaatual.com.br\/#organization"},"image":{"@id":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/#primaryimage"},"thumbnailUrl":"https:\/\/africaatual.com.br\/wp-content\/uploads\/2020\/08\/d2.jpeg","articleSection":["A Africa"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/","url":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/","name":"DAN\u00c7A NEGRA CONTEMPOR\u00c2NEA - EXISTIMOS, LOGO DAN\u00c7AMOS. - africaatual.com.br","isPartOf":{"@id":"https:\/\/africaatual.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/#primaryimage"},"image":{"@id":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/#primaryimage"},"thumbnailUrl":"https:\/\/africaatual.com.br\/wp-content\/uploads\/2020\/08\/d2.jpeg","datePublished":"2020-08-19T11:34:50+00:00","breadcrumb":{"@id":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/#primaryimage","url":"https:\/\/africaatual.com.br\/wp-content\/uploads\/2020\/08\/d2.jpeg","contentUrl":"https:\/\/africaatual.com.br\/wp-content\/uploads\/2020\/08\/d2.jpeg","width":960,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/africaatual.com.br\/index.php\/2020\/08\/19\/danca-negra-contemporanea-existimos-logo-dancamos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/africaatual.com.br\/"},{"@type":"ListItem","position":2,"name":"DAN\u00c7A NEGRA CONTEMPOR\u00c2NEA &#8211; EXISTIMOS, LOGO DAN\u00c7AMOS."}]},{"@type":"WebSite","@id":"https:\/\/africaatual.com.br\/#website","url":"https:\/\/africaatual.com.br\/","name":"africaatual.com.br","description":"O Atlas Geocultural da \u00c1frica \u00e9 um rico material de leitura e pesquisa, que visa apresentar de forma atual os pa\u00edses africanos, ainda t\u00e3o pouco conhecidos.","publisher":{"@id":"https:\/\/africaatual.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/africaatual.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/africaatual.com.br\/#organization","name":"africaatual.com.br","url":"https:\/\/africaatual.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/africaatual.com.br\/#\/schema\/logo\/image\/","url":"http:\/\/africaatual.com.br\/wp-content\/uploads\/2023\/06\/LOGOEIROS_Prancheta-1-tipo-preto.png","contentUrl":"http:\/\/africaatual.com.br\/wp-content\/uploads\/2023\/06\/LOGOEIROS_Prancheta-1-tipo-preto.png","width":1667,"height":730,"caption":"africaatual.com.br"},"image":{"@id":"https:\/\/africaatual.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/africaatual.com.br\/#\/schema\/person\/31315b203b16bec551dcad6d14ff6b17","name":"africaatual","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/62aeeba3c7bd20a0a9ee0e00da31fba130446f5c08871cd9335ec9bce29b9030?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/62aeeba3c7bd20a0a9ee0e00da31fba130446f5c08871cd9335ec9bce29b9030?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62aeeba3c7bd20a0a9ee0e00da31fba130446f5c08871cd9335ec9bce29b9030?s=96&d=mm&r=g","caption":"africaatual"},"sameAs":["http:\/\/africaatual.com.br"],"url":"https:\/\/africaatual.com.br\/index.php\/author\/atlasgeoculturalafricaatual-com\/"}]}},"_links":{"self":[{"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1336"}],"version-history":[{"count":0,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/media\/1337"}],"wp:attachment":[{"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1336"},{"taxonomy":"palavra-chave","embeddable":true,"href":"https:\/\/africaatual.com.br\/index.php\/wp-json\/wp\/v2\/palavra-chave?post=1336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}